{"id":55926,"date":"2019-07-15T12:50:20","date_gmt":"2019-07-15T15:50:20","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=55926"},"modified":"2019-07-15T12:50:20","modified_gmt":"2019-07-15T15:50:20","slug":"gustavo-garzon-llega-la-pampa-agosto","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/","title":{"rendered":"Gustavo Garz\u00f3n llega a La Pampa en agosto"},"content":{"rendered":"<p>La Secretar\u00eda de Cultura del Gobierno de La Pampa, a trav\u00e9s de la Direcci\u00f3n de Art\u00edstica invita el d\u00eda viernes 2 de agosto en el Auditorio del Centro Cultural Medasur a la <strong>presentaci\u00f3n del documental \u201cDown para arriba\u201d dirigido por Gustavo Garz\u00f3n<\/strong> quien estar\u00e1 presente en dicha ocasi\u00f3n, y a participar del<strong> Seminario de actuaci\u00f3n<\/strong> que el mismo Garz\u00f3n dictar\u00e1 al d\u00eda siguiente en el Centro de Artes Santa Rosa.<\/p>\n<p>Las funciones, todas gratuitas se realizar\u00e1n en el Centro Cultural Medasur (avenida. Belgrano Sur 180 \u2013 Santa Rosa) el viernes 2 de agosto, a las 10.30 horas y 15.30 horas y estar\u00e1n destinadas especialmente a instituciones, colegios secundarios, grupos y colectivos que de una u otra manera se encuentran comprometidos con el abordaje de la discapacidad.<\/p>\n<p>Para quienes acompa\u00f1en a grupos se solicit\u00f3 completar el formulario de inscripci\u00f3n ingresando al siguiente link: <a href=\"https:\/\/docs.google.com\/forms\/d\/1Ap4OkK-ta-sP9qIvcCXrOjDzAolTwsZEcC_m5uyFzh0\/viewform?edit_requested=true\" target=\"_blank\" rel=\"noopener\">https:\/\/docs.google.com\/forms\/d\/1Ap4OkK-ta-sP9qIvcCXrOjDzAolTwsZEcC_m5uyFzh0\/edit<\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-54069\" src=\"http:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzondownparaarriba233.jpg\" alt=\"\" width=\"679\" height=\"381\" srcset=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzondownparaarriba233.jpg 748w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzondownparaarriba233-300x168.jpg 300w, https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzondownparaarriba233-585x328.jpg 585w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/p>\n<p>El mismo viernes 2 de agosto a las 20:30, habr\u00e1 una proyecci\u00f3n gratuita y abierta para todo p\u00fablico. En este caso no se requiere inscripci\u00f3n previa.<\/p>\n<p>Esta propuesta busca mantener la reflexi\u00f3n abierta a distintas perspectivas sobre derechos y condiciones de las personas con discapacidad. En esta oportunidad, implica destacar el arte de la actuaci\u00f3n como un recurso fundamental para alcanzar otra forma de comunicaci\u00f3n interpersonal.<\/p>\n<p>En tanto el <strong>Seminario de actuaci\u00f3n<\/strong>\u00a0ser\u00e1 el s\u00e1bado 3 de agosto de 14 a 19 en el Centro de Artes, ubicado en Leguizam\u00f3n 1125.<\/p>\n<p>Dirigido a actores, estudiantes de teatro y p\u00fablico en general que sienta curiosidad por el arte de actuar. \u00datil para docentes y responsables de talleres. Se entregar\u00e1 diploma a los participantes con la intenci\u00f3n de reportar un beneficio curricular y para su desempe\u00f1o como docentes.<\/p>\n<p><strong>Seminario<\/strong><\/p>\n<p>El trabajo se basa en la relaci\u00f3n del actor con el texto. Para ello es necesario, aunque no condici\u00f3n excluyente, que los participantes lleven un texto memorizado. Ya sea una escena teatral que alguna vez hicieron, est\u00e9n haciendo o har\u00e1n, o una escena que preparen especialmente para el seminario. La escena puede ser entre dos o m\u00e1s asistentes al seminario y deber\u00e1 tener una duraci\u00f3n m\u00ednima de tres minutos y m\u00e1xima de 15 minutos. Tambi\u00e9n pueden presentar un mon\u00f3logo. El texto del mon\u00f3logo puede ser teatral o de un cuento o novela.<\/p>\n<p>El trabajo en el seminario se realiza a partir del trabajo sobre esos textos que muestran los participantes. Pero no excluye a aquellos que no lleven textos memorizados. Estos ser\u00e1n observadores activos del trabajo que realiza Garz\u00f3n con los que pasan a trabajar con sus textos. El seminario es din\u00e1mico y exigente, sin dejar nunca de ser recreativo y amable.<\/p>\n<p>Consultas e inscripciones: direcciondeartistica@gmail.com Tel: 42 4065. Int. 4792.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/UWlxOdrd6dI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n<strong>Sinopsis del film \u201cDown para arriba\u201d<\/strong><\/p>\n<p>En el barrio de Palermo los alumnos de la escuela de Juan Laso llegan a su clase de teatro. El grupo \u201cSin drama de Down\u201d funciona desde el a\u00f1o 2008 y est\u00e1 integrado en su totalidad por personas con s\u00edndrome de Down de edades que oscilan entre los veinticinco y cincuenta a\u00f1os.<\/p>\n<p>El objetivo de Juan es preparar a sus alumnos para la actuaci\u00f3n y que puedan llegar a desenvolverse profesionalmente. La voz en off de Gustavo Garz\u00f3n con toda la subjetividad de su mirada, es la gu\u00eda que organiza el documental desde un particular punto de vista: el de un padre de dos alumnos del taller y a su vez, actor.<\/p>\n<p>El desaf\u00edo consiste en filmar una pel\u00edcula de ficci\u00f3n, un cortometraje de unos 20 minutos de duraci\u00f3n cuyo gui\u00f3n surja de las mismas tem\u00e1ticas y conflictos que se plantean dentro del grupo. All\u00ed se muestra el minucioso seguimiento de todo el proceso: su construcci\u00f3n, la elecci\u00f3n de los temas y la trama, los ensayos y la filmaci\u00f3n propiamente dicha.<\/p>\n<p>Para conseguirlo, Juan debe superar la gran dificultad que implica introducir a las personas con capacidades diferentes en el mundo simb\u00f3lico de la actuaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Cultura del Gobierno de La Pampa, a trav\u00e9s de la Direcci\u00f3n de Art\u00edstica invita el d\u00eda viernes 2 de agosto en el Auditorio del Centro Cultural Medasur&hellip;<\/p>\n","protected":false},"author":4,"featured_media":54072,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,2],"tags":[],"class_list":["post-55926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-cultura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Cultura del Gobierno de La Pampa, a trav\u00e9s de la Direcci\u00f3n de Art\u00edstica invita el d\u00eda viernes 2 de agosto en el Auditorio del Centro Cultural Medasur&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T15:50:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"diario2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"diario2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/\"},\"author\":{\"name\":\"diario2\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\"},\"headline\":\"Gustavo Garz\u00f3n llega a La Pampa en agosto\",\"datePublished\":\"2019-07-15T15:50:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/\"},\"wordCount\":704,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/garzonseminarioactuacion45.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"CULTURA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/\",\"name\":\"Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/garzonseminarioactuacion45.jpg\",\"datePublished\":\"2019-07-15T15:50:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/garzonseminarioactuacion45.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/garzonseminarioactuacion45.jpg\",\"width\":632,\"height\":397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2019\\\/07\\\/15\\\/gustavo-garzon-llega-la-pampa-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gustavo Garz\u00f3n llega a La Pampa en agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/694f60677f23c4a530867a98f22b3768\",\"name\":\"diario2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g\",\"caption\":\"diario2\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/","og_locale":"es_ES","og_type":"article","og_title":"Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual","og_description":"La Secretar\u00eda de Cultura del Gobierno de La Pampa, a trav\u00e9s de la Direcci\u00f3n de Art\u00edstica invita el d\u00eda viernes 2 de agosto en el Auditorio del Centro Cultural Medasur&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2019-07-15T15:50:20+00:00","og_image":[{"width":632,"height":397,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg","type":"image\/jpeg"}],"author":"diario2","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"diario2","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/"},"author":{"name":"diario2","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768"},"headline":"Gustavo Garz\u00f3n llega a La Pampa en agosto","datePublished":"2019-07-15T15:50:20+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/"},"wordCount":704,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg","articleSection":["A - QUE PASA (al costado)","CULTURA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/","name":"Gustavo Garz\u00f3n llega a La Pampa en agosto - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg","datePublished":"2019-07-15T15:50:20+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2019\/06\/garzonseminarioactuacion45.jpg","width":632,"height":397},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2019\/07\/15\/gustavo-garzon-llega-la-pampa-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Gustavo Garz\u00f3n llega a La Pampa en agosto"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/694f60677f23c4a530867a98f22b3768","name":"diario2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a2567495ba16b852fcd8f1ed006a2e24fcace936018ed8237e95f488ad6e0a7?s=96&d=mm&r=g","caption":"diario2"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario2\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/55926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=55926"}],"version-history":[{"count":1,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/55926\/revisions"}],"predecessor-version":[{"id":55929,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/55926\/revisions\/55929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/54072"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=55926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=55926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=55926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}