{"id":96061,"date":"2020-06-02T18:19:54","date_gmt":"2020-06-02T21:19:54","guid":{"rendered":"http:\/\/diariotextual.com\/inicio\/?p=96061"},"modified":"2020-06-02T19:04:39","modified_gmt":"2020-06-02T22:04:39","slug":"la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva","status":"publish","type":"post","link":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/","title":{"rendered":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa"},"content":{"rendered":"<p>La Uni\u00f3n C\u00edvica Radical pidi\u00f3 a las autoridades del Gobierno provincial que indiquen qu\u00e9 protocolos de seguridad, para prevenir el coronavirus Covid-19, seguir\u00e1n <a href=\"http:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/viernes-llega-alberto-fernandez-la-pampa\/\" target=\"_blank\" rel=\"noopener\"><strong>el viernes en su visita a La Pampa el presidente Alberto Fern\u00e1ndez<\/strong><\/a>, el ministro Wado de Pedro, otros funcionarios y la custodia presidencial.<\/p>\n<p>Tito Pech\u00edn, presidente del radicalismo pampeano, difundi\u00f3 una nota en la que <strong>pareci\u00f3 deslizar que reclamaba que el jefe de Estado y la comitiva deb\u00edan cumplir una cuarentena de 14 d\u00edas al ingresar a La Pampa<\/strong>, como el resto de la poblaci\u00f3n. Sin embargo, lo desminti\u00f3. \u00abEstamos pidiendo -dijo al ser consultado por Diario Textual- que el Gobierno provincial diga cu\u00e1les son los protocolos que va a seguir la comitida y la custodia\u00bb.<\/p>\n<p>Precisamente no pueden exigir que el presidente cumpla con una cuarentena al ingresar a la provincia: <strong>el art\u00edculo sexto del decreto 297\/20 establece que \u00abquedan exceptuados del cumplimiento del Aislamiento Social Preventivo y Oblogatorio las autoridades superiores de los gobiernos Nacional, Provinial, Municiales y de CABA\u00bb<\/strong>.<\/p>\n<p>\u00bfQu\u00e9 dice la nota? \u201cDesde el Comit\u00e9 Provincia de La Pampa de la Uni\u00f3n C\u00edvica Radical vemos con total agrado la visita del se\u00f1or presidente de la Naci\u00f3n\u201d, expresa.<\/p>\n<p>\u201cLos ciudadanos -agrega- ven restringida su salida e ingreso a La Pampa. D\u00edas pasados se bloquearon siete puestos camineros, impidiendo el tr\u00e1nsito entre localidades vecinas con todos los inconvenientes que ellos conlleva. Cada trabajador que necesite por sus funciones salir o ingresar a la provincia, o hasta nuestros mismos legisladores nacionales, deben dar cumplimiento al decreto que rige en la actualidad. El mismo obliga a cualquier ciudadano a cumplir 14 d\u00edas de aislamiento en el ingreso o regreso de La Pampa\u201d.<\/p>\n<p>\u201cDesde nuestro partido siempre hemos bregado por la Rep\u00fablica, donde todos los poderes del Estado cumplan con su rol fundamental en estos tiempos que estamos atravesando\u201d, dijo. \u201cTodos los habitantes tenemos el mismo derecho, la ley debe ser pareja y es por ese motivo entendemos se debe informar a la ciudadan\u00eda, la cual ha cumplido de manera eficaz con lo decretado por el Gobierno provincial, cu\u00e1les ser\u00e1n las obligaciones de las personas que ingresan en la comitiva presidencial. Bienvenido se\u00f1or presidente\u201d.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"QqsnZ6qlwE\"><p><a href=\"http:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/viernes-llega-alberto-fernandez-la-pampa\/\">El viernes llega Alberto Fern\u00e1ndez a La Pampa<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/viernes-llega-alberto-fernandez-la-pampa\/embed\/#?secret=QqsnZ6qlwE\" data-secret=\"QqsnZ6qlwE\" width=\"600\" height=\"338\" title=\"&#171;El viernes llega Alberto Fern\u00e1ndez a La Pampa&#187; &#8212; Diario Textual\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n C\u00edvica Radical pidi\u00f3 a las autoridades del Gobierno provincial que indiquen qu\u00e9 protocolos de seguridad, para prevenir el coronavirus Covid-19, seguir\u00e1n el viernes en su visita a La&hellip;<\/p>\n","protected":false},"author":3,"featured_media":96068,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-96061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que-pasa","category-politica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual\" \/>\n<meta property=\"og:description\" content=\"La Uni\u00f3n C\u00edvica Radical pidi\u00f3 a las autoridades del Gobierno provincial que indiquen qu\u00e9 protocolos de seguridad, para prevenir el coronavirus Covid-19, seguir\u00e1n el viernes en su visita a La&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Textual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eltextual\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-02T21:19:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-02T22:04:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1288\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario1 Diario1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eltextual\" \/>\n<meta name=\"twitter:site\" content=\"@eltextual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario1 Diario1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/\"},\"author\":{\"name\":\"Diario1 Diario1\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\"},\"headline\":\"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa\",\"datePublished\":\"2020-06-02T21:19:54+00:00\",\"dateModified\":\"2020-06-02T22:04:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/\"},\"wordCount\":406,\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fernandezalbertocoronavirustelam2020-100.jpg\",\"articleSection\":[\"A - QUE PASA (al costado)\",\"POLITICA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/\",\"name\":\"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fernandezalbertocoronavirustelam2020-100.jpg\",\"datePublished\":\"2020-06-02T21:19:54+00:00\",\"dateModified\":\"2020-06-02T22:04:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fernandezalbertocoronavirustelam2020-100.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/fernandezalbertocoronavirustelam2020-100.jpg\",\"width\":1288,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/2020\\\/06\\\/02\\\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#website\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"name\":\"Diario Textual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#organization\",\"name\":\"Diario Textual\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logotextual1.jpg\",\"width\":516,\"height\":76,\"caption\":\"Diario Textual\"},\"image\":{\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eltextual\",\"https:\\\/\\\/x.com\\\/eltextual\",\"http:\\\/\\\/www.instagram.com\\\/eltextual\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/#\\\/schema\\\/person\\\/418fc4093c33e86ed41562db3508f958\",\"name\":\"Diario1 Diario1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g\",\"caption\":\"Diario1 Diario1\"},\"url\":\"https:\\\/\\\/diariotextual.com\\\/inicio\\\/index.php\\\/author\\\/diario1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/","og_locale":"es_ES","og_type":"article","og_title":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual","og_description":"La Uni\u00f3n C\u00edvica Radical pidi\u00f3 a las autoridades del Gobierno provincial que indiquen qu\u00e9 protocolos de seguridad, para prevenir el coronavirus Covid-19, seguir\u00e1n el viernes en su visita a La&hellip;","og_url":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/","og_site_name":"Diario Textual","article_publisher":"https:\/\/www.facebook.com\/eltextual","article_published_time":"2020-06-02T21:19:54+00:00","article_modified_time":"2020-06-02T22:04:39+00:00","og_image":[{"width":1288,"height":768,"url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg","type":"image\/jpeg"}],"author":"Diario1 Diario1","twitter_card":"summary_large_image","twitter_creator":"@eltextual","twitter_site":"@eltextual","twitter_misc":{"Escrito por":"Diario1 Diario1","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#article","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/"},"author":{"name":"Diario1 Diario1","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958"},"headline":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa","datePublished":"2020-06-02T21:19:54+00:00","dateModified":"2020-06-02T22:04:39+00:00","mainEntityOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/"},"wordCount":406,"publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg","articleSection":["A - QUE PASA (al costado)","POLITICA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/","url":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/","name":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa - Diario Textual","isPartOf":{"@id":"https:\/\/diariotextual.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#primaryimage"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#primaryimage"},"thumbnailUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg","datePublished":"2020-06-02T21:19:54+00:00","dateModified":"2020-06-02T22:04:39+00:00","breadcrumb":{"@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#primaryimage","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2020\/06\/fernandezalbertocoronavirustelam2020-100.jpg","width":1288,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/diariotextual.com\/inicio\/index.php\/2020\/06\/02\/la-ucr-pide-conocer-cuales-los-protocolos-seguiran-alberto-la-comitiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariotextual.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"La UCR pide conocer cu\u00e1les son los protocolos que seguir\u00e1n Alberto y la comitiva en La Pampa"}]},{"@type":"WebSite","@id":"https:\/\/diariotextual.com\/inicio\/#website","url":"https:\/\/diariotextual.com\/inicio\/","name":"Diario Textual","description":"","publisher":{"@id":"https:\/\/diariotextual.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariotextual.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariotextual.com\/inicio\/#organization","name":"Diario Textual","url":"https:\/\/diariotextual.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/","url":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","contentUrl":"https:\/\/diariotextual.com\/inicio\/wp-content\/uploads\/2023\/05\/logotextual1.jpg","width":516,"height":76,"caption":"Diario Textual"},"image":{"@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eltextual","https:\/\/x.com\/eltextual","http:\/\/www.instagram.com\/eltextual"]},{"@type":"Person","@id":"https:\/\/diariotextual.com\/inicio\/#\/schema\/person\/418fc4093c33e86ed41562db3508f958","name":"Diario1 Diario1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9167d280179c85bc18be67aa7eda765854300033af4896dd779b608640f2ef7a?s=96&d=mm&r=g","caption":"Diario1 Diario1"},"url":"https:\/\/diariotextual.com\/inicio\/index.php\/author\/diario1\/"}]}},"_links":{"self":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/96061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=96061"}],"version-history":[{"count":6,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/96061\/revisions"}],"predecessor-version":[{"id":96077,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/96061\/revisions\/96077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media\/96068"}],"wp:attachment":[{"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=96061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=96061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariotextual.com\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=96061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}